{"id":2435,"date":"2020-12-04T04:51:19","date_gmt":"2020-12-03T21:51:19","guid":{"rendered":"https:\/\/www.hiqfood.com\/?page_id=2435"},"modified":"2024-02-05T15:35:42","modified_gmt":"2024-02-05T08:35:42","slug":"about","status":"publish","type":"page","link":"https:\/\/www.hiqfood.com\/en\/about\/","title":{"rendered":"About Us"},"content":{"rendered":"<h4 class=\"font-weight-bold mb-3\">\u0e27\u0e34\u0e16\u0e35&#8230;\u0e44\u0e2e\u0e04\u0e34\u0e27<\/h4>\n<h1 class=\"font-weight-bold mb-4\">\u201c\u0e04\u0e38\u0e13\u0e04\u0e48\u0e32&#8230;\u0e2d\u0e22\u0e39\u0e48\u0e43\u0e19\u0e2a\u0e34\u0e48\u0e07\u0e17\u0e35\u0e48\u0e40\u0e23\u0e32\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e17\u0e33\u201d<\/h1>\n<p>\u0e04\u0e27\u0e32\u0e21\u0e21\u0e38\u0e48\u0e07\u0e21\u0e31\u0e48\u0e19\u0e43\u0e19\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e \u0e2b\u0e31\u0e27\u0e43\u0e08\u0e2a\u0e39\u0e48\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u0e27\u0e34\u0e16\u0e35&#8230;\u0e44\u0e2e\u0e04\u0e34\u0e27 \u201c\u0e04\u0e38\u0e13\u0e04\u0e48\u0e32&#8230;\u0e2d\u0e22\u0e39\u0e48\u0e43\u0e19\u0e2a\u0e34\u0e48\u0e07\u0e17\u0e35\u0e48\u0e40\u0e23\u0e32\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e17\u0e33\u201d \u0e04\u0e27\u0e32\u0e21\u0e21\u0e38\u0e48\u0e07\u0e21\u0e31\u0e48\u0e19\u0e43\u0e19\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e \u0e2b\u0e31\u0e27\u0e43\u0e08\u0e2a\u0e39\u0e48\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-templates\/about.php","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-2435","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>About Us | Hi-Q Food Products Co., Ltd.<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.hiqfood.com\/en\/about\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"About Us | Hi-Q Food Products Co., Ltd.\" \/>\n<meta property=\"og:description\" content=\"\u0e27\u0e34\u0e16\u0e35&#8230;\u0e44\u0e2e\u0e04\u0e34\u0e27 \u201c\u0e04\u0e38\u0e13\u0e04\u0e48\u0e32&#8230;\u0e2d\u0e22\u0e39\u0e48\u0e43\u0e19\u0e2a\u0e34\u0e48\u0e07\u0e17\u0e35\u0e48\u0e40\u0e23\u0e32\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e17\u0e33\u201d \u0e04\u0e27\u0e32\u0e21\u0e21\u0e38\u0e48\u0e07\u0e21\u0e31\u0e48\u0e19\u0e43\u0e19\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e \u0e2b\u0e31\u0e27\u0e43\u0e08\u0e2a\u0e39\u0e48\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.hiqfood.com\/en\/about\/\" \/>\n<meta property=\"og:site_name\" content=\"Hi-Q Food Products Co., Ltd.\" \/>\n<meta property=\"article:modified_time\" content=\"2024-02-05T08:35:42+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.hiqfood.com\/en\/about\/\",\"url\":\"https:\/\/www.hiqfood.com\/en\/about\/\",\"name\":\"About Us | Hi-Q Food Products Co., Ltd.\",\"isPartOf\":{\"@id\":\"https:\/\/www.hiqfood.com\/#website\"},\"datePublished\":\"2020-12-03T21:51:19+00:00\",\"dateModified\":\"2024-02-05T08:35:42+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.hiqfood.com\/en\/about\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.hiqfood.com\/en\/about\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.hiqfood.com\/en\/about\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.hiqfood.com\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"About Us\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.hiqfood.com\/#website\",\"url\":\"https:\/\/www.hiqfood.com\/\",\"name\":\"Hi-Q Food Products Co., Ltd.\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.hiqfood.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"About Us | Hi-Q Food Products Co., Ltd.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.hiqfood.com\/en\/about\/","og_locale":"en_US","og_type":"article","og_title":"About Us | Hi-Q Food Products Co., Ltd.","og_description":"\u0e27\u0e34\u0e16\u0e35&#8230;\u0e44\u0e2e\u0e04\u0e34\u0e27 \u201c\u0e04\u0e38\u0e13\u0e04\u0e48\u0e32&#8230;\u0e2d\u0e22\u0e39\u0e48\u0e43\u0e19\u0e2a\u0e34\u0e48\u0e07\u0e17\u0e35\u0e48\u0e40\u0e23\u0e32\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e17\u0e33\u201d \u0e04\u0e27\u0e32\u0e21\u0e21\u0e38\u0e48\u0e07\u0e21\u0e31\u0e48\u0e19\u0e43\u0e19\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e \u0e2b\u0e31\u0e27\u0e43\u0e08\u0e2a\u0e39\u0e48\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08","og_url":"https:\/\/www.hiqfood.com\/en\/about\/","og_site_name":"Hi-Q Food Products Co., Ltd.","article_modified_time":"2024-02-05T08:35:42+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.hiqfood.com\/en\/about\/","url":"https:\/\/www.hiqfood.com\/en\/about\/","name":"About Us | Hi-Q Food Products Co., Ltd.","isPartOf":{"@id":"https:\/\/www.hiqfood.com\/#website"},"datePublished":"2020-12-03T21:51:19+00:00","dateModified":"2024-02-05T08:35:42+00:00","breadcrumb":{"@id":"https:\/\/www.hiqfood.com\/en\/about\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.hiqfood.com\/en\/about\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.hiqfood.com\/en\/about\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.hiqfood.com\/en\/"},{"@type":"ListItem","position":2,"name":"About Us"}]},{"@type":"WebSite","@id":"https:\/\/www.hiqfood.com\/#website","url":"https:\/\/www.hiqfood.com\/","name":"Hi-Q Food Products Co., Ltd.","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.hiqfood.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/www.hiqfood.com\/en\/wp-json\/wp\/v2\/pages\/2435","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hiqfood.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.hiqfood.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.hiqfood.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.hiqfood.com\/en\/wp-json\/wp\/v2\/comments?post=2435"}],"version-history":[{"count":9,"href":"https:\/\/www.hiqfood.com\/en\/wp-json\/wp\/v2\/pages\/2435\/revisions"}],"predecessor-version":[{"id":10438,"href":"https:\/\/www.hiqfood.com\/en\/wp-json\/wp\/v2\/pages\/2435\/revisions\/10438"}],"wp:attachment":[{"href":"https:\/\/www.hiqfood.com\/en\/wp-json\/wp\/v2\/media?parent=2435"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}